{"id":8328,"date":"2019-10-09T15:01:31","date_gmt":"2019-10-09T07:01:31","guid":{"rendered":"https:\/\/www.jxscmachine.com\/?post_type=new&#038;p=8328"},"modified":"2019-10-09T15:03:01","modified_gmt":"2019-10-09T07:03:01","slug":"comparaison-de-5-types-de-concasseurs-a-cone","status":"publish","type":"new","link":"https:\/\/www.jxscmachine.com\/fr\/new\/5-types-of-cone-crushers-comparison\/","title":{"rendered":"Comparaison des 5 types de concasseurs \u00e0 c\u00f4ne"},"content":{"rendered":"<p><strong>Concasseur \u00e0 c\u00f4ne<\/strong> est l'un des \u00e9quipements miniers les plus utilis\u00e9s. Ce document pr\u00e9sente une description et une comparaison entre les <strong>5 types de concasseurs \u00e0 c\u00f4ne<\/strong>pour vous aider \u00e0 choisir le bon.<\/p>\n<p><span style=\"font-family: 'comic sans ms', sans-serif; font-size: 15pt;\">L'\u00e9quipe d'ing\u00e9nieurs de JXSC vous aide \u00e0 acheter le concasseur \u00e0 c\u00f4ne et \u00e0 concevoir un circuit de concassage complet. Apprenez \u00e0 conna\u00eetre nos <a href=\"https:\/\/www.jxscmachine.com\/fr\/concasseur-de-roches\/concasseur-a-cone\/\">machine \u00e0 concasser les c\u00f4nes<\/a> page produit, discutez avec nous du mod\u00e8le et du prix.<\/span><\/p>\n<h2>Concasseur \u00e0 c\u00f4ne Simmons<\/h2>\n<p>\u3010<strong>Application<\/strong>\u3011 Le concasseur \u00e0 c\u00f4ne Simmons est un concasseur moyen ou un concasseur fin utilis\u00e9 dans les sites ne n\u00e9cessitant pas une granulom\u00e9trie \u00e9lev\u00e9e.<br \/>\n\u00c9tant donn\u00e9 que le concasseur \u00e0 c\u00f4ne Simmons contr\u00f4le la taille du produit en r\u00e9duisant la taille de l'ouverture de d\u00e9charge, il n'est pas adapt\u00e9 au concassage superficiel et \u00e0 la fabrication de sable.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-8330\" src=\"https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/Simmons-cone-crusher.jpg\" alt=\"Concasseur \u00e0 c\u00f4ne Simmons\" width=\"800\" height=\"572\" srcset=\"https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/Simmons-cone-crusher.jpg 800w, https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/Simmons-cone-crusher-300x215.jpg 300w, https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/Simmons-cone-crusher-768x549.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>\u3010<strong>Avantages<\/strong>\u3011 prix bas, performances stables, exp\u00e9rience en mati\u00e8re d'utilisation et de maintenance.<\/p>\n<p>\u3010<strong>Inconv\u00e9nients<\/strong>\u3011 En termes de structure, il est beaucoup plus lourd que le concasseur \u00e0 c\u00f4ne hydraulique monocylindre de la m\u00eame sp\u00e9cification, associ\u00e9 \u00e0 une petite force de broyage, un faible rendement, le concasseur \u00e0 c\u00f4ne Simmons est progressivement remplac\u00e9 par un concasseur \u00e0 c\u00f4ne hydraulique \u00e0 broyage par stratification efficace.<\/p>\n<p>\u3010<strong>D\u00e9veloppement<\/strong>\u3011 Sur la base du concasseur \u00e0 c\u00f4ne Simmons d'origine, le fabricant chinois de concasseurs \u00e0 c\u00f4ne a ajout\u00e9 une fonction de chambre de compensation hydraulique, appel\u00e9e \"chambre de compensation\". <em>concasseur \u00e0 c\u00f4ne compos\u00e9<\/em>.<\/p>\n<h2>Concasseur \u00e0 c\u00f4ne giratoire<\/h2>\n<p>\u3010<strong>Application<\/strong>\u3011 Le concasseur \u00e0 c\u00f4ne giratoire convient \u00e0 la quatri\u00e8me \u00e9tape de concassage des mat\u00e9riaux moyennement durs. La forme sp\u00e9ciale de sa cavit\u00e9 de concassage permet d'effectuer un concassage par laminage et d'obtenir un produit de petite granularit\u00e9, m\u00eame si la taille de d\u00e9charge est importante.<br \/>\nC'est pourquoi le concasseur \u00e0 c\u00f4ne rotatif est aussi souvent appel\u00e9 concasseur superfine.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-8335\" src=\"https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/Gyratory-cone-crusher.jpg\" alt=\"Concasseur \u00e0 c\u00f4ne giratoire\" width=\"800\" height=\"524\" srcset=\"https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/Gyratory-cone-crusher.jpg 800w, https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/Gyratory-cone-crusher-300x197.jpg 300w, https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/Gyratory-cone-crusher-768x503.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>\u3010<strong>Avantages<\/strong>\u3011 Une granulom\u00e9trie qualifi\u00e9e et une bonne forme. Le concassage rotatif \u00e0 c\u00f4ne permet non seulement de fournir au broyeur des mati\u00e8res premi\u00e8res \u00e0 grain plus fin, mais il constitue \u00e9galement un \u00e9quipement important pour l'usine de fabrication de sable.<\/p>\n<p>\u3010<strong>Inconv\u00e9nients<\/strong>\u3011 Consommation d'\u00e9nergie \u00e9lev\u00e9e, poids \u00e9lev\u00e9 et faible rendement. Avec le d\u00e9veloppement de la haute capacit\u00e9, le concasseur \u00e0 c\u00f4ne rotatif sera progressivement remplac\u00e9 par le concasseur \u00e0 c\u00f4ne hydraulique.<\/p>\n<h2>Concasseur \u00e0 c\u00f4ne hydraulique monocylindre<\/h2>\n<p>\u3010<strong>Application<\/strong>\u3011 Le concasseur \u00e0 c\u00f4ne hydraulique monocylindre convient au concassage de duret\u00e9 moyenne, au concassage fin et m\u00eame au concassage ultrafin.<br \/>\n\u3010<strong>Avantages<\/strong>\u3011 Structure simple, faible co\u00fbt de fabrication et performances stables.<br \/>\nC\u00f4ne abrupt, haute fr\u00e9quence d'oscillation, faible excentricit\u00e9, structure simple, contr\u00f4le automatique facile, force de broyage et fluctuation de puissance faibles.<br \/>\nL'angle excentrique r\u00e9duit de l'arbre principal et la longue chambre de broyage am\u00e9liorent l'uniformit\u00e9 du mat\u00e9riau broy\u00e9. Le produit a une taille de particule uniforme et moins de mati\u00e8re en forme d'aiguille.<\/p>\n<p>\u3010<strong>Inconv\u00e9nients<\/strong>\u3011 La force de broyage du concasseur \u00e0 c\u00f4ne hydraulique monocylindre est l\u00e9g\u00e8rement insuffisante, en particulier pour le broyage de mat\u00e9riaux durs.<br \/>\nLe c\u00f4ne mobile de levage, si l'alimentation est in\u00e9gale, la paroi de roulement n'est pas us\u00e9e de mani\u00e8re uniforme.<br \/>\nLe cylindre se trouve en bas, l'espace de travail inf\u00e9rieur est petit, ce qui entra\u00eene certaines difficult\u00e9s de maintenance.<\/p>\n<h2>Concasseur \u00e0 c\u00f4ne hydraulique multi-cylindres<\/h2>\n<p>\u3010<strong>Application<\/strong>\u3011 Le concasseur \u00e0 c\u00f4ne hydraulique multi-cylindres poss\u00e8de une grande force de concassage et convient au concassage de mat\u00e9riaux durs. Les mat\u00e9riaux plus petits que la bouche de d\u00e9charge peuvent m\u00eame repr\u00e9senter 70%~80% de la quantit\u00e9 de traitement.<\/p>\n<p>\u3010<strong>Avantages<\/strong>\u3011 Haute fr\u00e9quence d'oscillation, grande excentricit\u00e9, c\u00f4ne lent, verrouillage hydraulique multicylindre autour, l'arbre principal est en forme de support de poutre en porte-\u00e0-faux et la structure de support de tuile sph\u00e9rique, en utilisant le moteur hydraulique pour ajuster le c\u00f4ne fixe.<\/p>\n<p>\u3010<strong>Inconv\u00e9nients<\/strong>\u3011 Un petit rayon sph\u00e9rique R et un petit rayon d'oscillation provoquent facilement des ph\u00e9nom\u00e8nes instables tels que l'oscillation du c\u00f4ne mobile, le renversement, un mauvais contact entre l'arbre principal et la bague, ce qui affecte le fonctionnement normal de la machine.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-8340\" src=\"https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/single-cylinder-hydraulic-cone-crusher.jpg\" alt=\"concasseur monocylindre-multi-cylindre-hydraulique \u00e0 c\u00f4ne\" width=\"800\" height=\"396\" srcset=\"https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/single-cylinder-hydraulic-cone-crusher.jpg 800w, https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/single-cylinder-hydraulic-cone-crusher-300x149.jpg 300w, https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/single-cylinder-hydraulic-cone-crusher-768x380.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<h3><span style=\"background-color: #c7c1c1;\">Concasseur hydraulique \u00e0 c\u00f4ne monocylindre VS multicylindre<\/span><\/h3>\n<p>En termes de performance de concassage, le concasseur \u00e0 c\u00f4ne hydraulique multi-cylindres est g\u00e9n\u00e9ralement plus \u00e9lev\u00e9, sa force de concassage et son rapport de concassage sont plus importants, la plage de r\u00e9glage de la d\u00e9charge est plus large, ce qui permet une plus grande flexibilit\u00e9 dans le r\u00e9glage de la qualit\u00e9 du produit.<br \/>\nIl est sup\u00e9rieur au concasseur \u00e0 c\u00f4ne monocylindre en termes de performances et de qualit\u00e9 des produits concass\u00e9s. Toutefois, l'utilisation d'un ou de plusieurs cylindres dans l'ensemble du processus d\u00e9pend de la configuration de l'ensemble du processus.<\/p>\n<p>Le concasseur \u00e0 c\u00f4ne hydraulique multicylindre est utilis\u00e9 pour r\u00e9duire le nombre d'\u00e9tapes de concassage et l'investissement. La teneur en aiguilles est g\u00e9n\u00e9ralement inf\u00e9rieure \u00e0 15%.<\/p>\n<p>Pour le concassage de roches dures, choisissez un concasseur hydraulique \u00e0 c\u00f4nes multicylindres ; pour le concassage de roches de duret\u00e9 g\u00e9n\u00e9rale, choisissez un concasseur hydraulique \u00e0 c\u00f4nes monocylindres.<\/p>\n<h2>Concasseur \u00e0 c\u00f4ne \u00e0 inertie<\/h2>\n<p>\u3010<strong>Application<\/strong>\u3011 Le concasseur \u00e0 c\u00f4ne \u00e0 inertie a un grand rapport de broyage et peut obtenir des produits \u00e0 grains tr\u00e8s fins. Il est utilis\u00e9 pour le concassage ultrafin ou la fabrication de sable artificiel, et son effet est meilleur que celui des autres types de concasseurs \u00e0 c\u00f4ne.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-8345\" src=\"https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/Inertia-cone-crusher.jpg\" alt=\"Concasseur \u00e0 c\u00f4ne \u00e0 inertie\" width=\"800\" height=\"491\" srcset=\"https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/Inertia-cone-crusher.jpg 800w, https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/Inertia-cone-crusher-300x184.jpg 300w, https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/Inertia-cone-crusher-768x471.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>\u3010<strong>Avantages<\/strong>\u3011 Le principe de fonctionnement du concasseur \u00e0 c\u00f4ne \u00e0 inertie est unique. Il s'agit d'un nouveau type d'\u00e9quipement de concassage ultrafin avec un bon effet de \"pulv\u00e9risation en couches\". Le produit de concassage en circuit ouvert a une granularit\u00e9 de quelques millim\u00e8tres, ce qui peut r\u00e9pondre aux exigences de la nouvelle technologie \"multi-broyage et moins de broyage\", r\u00e9duire consid\u00e9rablement la consommation d'\u00e9nergie et la consommation d'acier du processus de broyage.<\/p>\n<p>\u3010<strong>Inconv\u00e9nients<\/strong>\u3011 Lourd, il p\u00e8se environ deux fois plus que les autres concasseurs \u00e0 c\u00f4ne.<\/p>\n<h2>En bref<\/h2>\n<p>La comparaison ci-dessus des performances et des caract\u00e9ristiques des diff\u00e9rents types de concasseurs \u00e0 c\u00f4ne peut servir de r\u00e9f\u00e9rence pour la s\u00e9lection du mat\u00e9riel de concassage.<br \/>\nUne fois le type de machine s\u00e9lectionn\u00e9, la taille et la quantit\u00e9 des sp\u00e9cifications sp\u00e9cifiques sont choisies en fonction de la relation de configuration avec d'autres dispositifs et de la variation du taux de charge afin d'atteindre l'objectif de production escompt\u00e9.<\/p>\n<hr>\n<p>JXSC est un fabricant chinois d'\u00e9quipements miniers qui existe depuis 35 ans et qui fournit diff\u00e9rents types d'\u00e9quipements miniers. <a href=\"https:\/\/www.jxscmachine.com\/fr\/categorie\/concasseur-de-roches\/\">concasseurs de roches<\/a> pour les mines, les usines de sable et l'industrie de la construction.<br \/>\nProduits chauds : Concasseur \u00e0 m\u00e2choires, concasseur \u00e0 c\u00f4nes, concasseur \u00e0 percussion, concasseur \u00e0 marteaux, concasseur \u00e0 rouleaux.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le concasseur \u00e0 c\u00f4ne est l'un des \u00e9quipements miniers les plus utilis\u00e9s. Cet article d\u00e9crit et compare les cinq types de concasseurs \u00e0 c\u00f4ne afin de vous aider \u00e0 choisir le bon. L'\u00e9quipe d'ing\u00e9nieurs de JXSC vous aide \u00e0 acheter le concasseur \u00e0 c\u00f4ne et \u00e0 concevoir un circuit de concassage complet. D\u00e9couvrez notre concasseur \u00e0 c\u00f4ne ... <a href=\"https:\/\/www.jxscmachine.com\/fr\/new\/5-types-of-cone-crushers-comparison\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Comparaison des 5 types de concasseurs \u00e0 c\u00f4ne<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":8350,"parent":0,"menu_order":291,"comment_status":"open","ping_status":"open","template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[],"tags":[],"class_list":["post-8328","new","type-new","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5 Types of Cone Crushers Comparison - JXSC Machine<\/title>\n<meta name=\"description\" content=\"This paper makes a description and comparison between the 5 types of cone crushers, to help you choose the right one. Cone crusher is one of the most widely used mining equipment.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jxscmachine.com\/fr\/nouveau\/comparaison-de-5-types-de-concasseurs-a-cone\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 Types of Cone Crushers Comparison - JXSC Machine\" \/>\n<meta property=\"og:description\" content=\"This paper makes a description and comparison between the 5 types of cone crushers, to help you choose the right one. Cone crusher is one of the most widely used mining equipment.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jxscmachine.com\/fr\/nouveau\/comparaison-de-5-types-de-concasseurs-a-cone\/\" \/>\n<meta property=\"og:site_name\" content=\"JXSC Machine\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-09T07:03:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/cone-crushers-supplier.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"776\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jxscmachine.com\\\/new\\\/5-types-of-cone-crushers-comparison\\\/\",\"url\":\"https:\\\/\\\/www.jxscmachine.com\\\/new\\\/5-types-of-cone-crushers-comparison\\\/\",\"name\":\"5 Types of Cone Crushers Comparison - JXSC Machine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jxscmachine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jxscmachine.com\\\/new\\\/5-types-of-cone-crushers-comparison\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jxscmachine.com\\\/new\\\/5-types-of-cone-crushers-comparison\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jxscmachine.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/cone-crushers-supplier.jpg\",\"datePublished\":\"2019-10-09T07:01:31+00:00\",\"dateModified\":\"2019-10-09T07:03:01+00:00\",\"description\":\"This paper makes a description and comparison between the 5 types of cone crushers, to help you choose the right one. Cone crusher is one of the most widely used mining equipment.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jxscmachine.com\\\/new\\\/5-types-of-cone-crushers-comparison\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jxscmachine.com\\\/new\\\/5-types-of-cone-crushers-comparison\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.jxscmachine.com\\\/new\\\/5-types-of-cone-crushers-comparison\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jxscmachine.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/cone-crushers-supplier.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jxscmachine.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/cone-crushers-supplier.jpg\",\"width\":776,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jxscmachine.com\\\/new\\\/5-types-of-cone-crushers-comparison\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jxscmachine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.jxscmachine.com\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"5 Types of Cone Crushers Comparison\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jxscmachine.com\\\/#website\",\"url\":\"https:\\\/\\\/www.jxscmachine.com\\\/\",\"name\":\"JXSC Machine\",\"description\":\"40+ Years&#039; Mineral Separating Equipment Manufacturer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jxscmachine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comparaison de 5 types de concasseurs \u00e0 c\u00f4ne - JXSC Machine","description":"Ce document d\u00e9crit et compare les cinq types de concasseurs \u00e0 c\u00f4ne afin de vous aider \u00e0 choisir le bon. Le concasseur \u00e0 c\u00f4ne est l'un des \u00e9quipements miniers les plus utilis\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jxscmachine.com\/fr\/nouveau\/comparaison-de-5-types-de-concasseurs-a-cone\/","og_locale":"fr_FR","og_type":"article","og_title":"5 Types of Cone Crushers Comparison - JXSC Machine","og_description":"This paper makes a description and comparison between the 5 types of cone crushers, to help you choose the right one. Cone crusher is one of the most widely used mining equipment.","og_url":"https:\/\/www.jxscmachine.com\/fr\/nouveau\/comparaison-de-5-types-de-concasseurs-a-cone\/","og_site_name":"JXSC Machine","article_modified_time":"2019-10-09T07:03:01+00:00","og_image":[{"width":776,"height":550,"url":"https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/cone-crushers-supplier.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jxscmachine.com\/new\/5-types-of-cone-crushers-comparison\/","url":"https:\/\/www.jxscmachine.com\/new\/5-types-of-cone-crushers-comparison\/","name":"Comparaison de 5 types de concasseurs \u00e0 c\u00f4ne - JXSC Machine","isPartOf":{"@id":"https:\/\/www.jxscmachine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jxscmachine.com\/new\/5-types-of-cone-crushers-comparison\/#primaryimage"},"image":{"@id":"https:\/\/www.jxscmachine.com\/new\/5-types-of-cone-crushers-comparison\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/cone-crushers-supplier.jpg","datePublished":"2019-10-09T07:01:31+00:00","dateModified":"2019-10-09T07:03:01+00:00","description":"Ce document d\u00e9crit et compare les cinq types de concasseurs \u00e0 c\u00f4ne afin de vous aider \u00e0 choisir le bon. Le concasseur \u00e0 c\u00f4ne est l'un des \u00e9quipements miniers les plus utilis\u00e9s.","breadcrumb":{"@id":"https:\/\/www.jxscmachine.com\/new\/5-types-of-cone-crushers-comparison\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jxscmachine.com\/new\/5-types-of-cone-crushers-comparison\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jxscmachine.com\/new\/5-types-of-cone-crushers-comparison\/#primaryimage","url":"https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/cone-crushers-supplier.jpg","contentUrl":"https:\/\/www.jxscmachine.com\/wp-content\/uploads\/2019\/10\/cone-crushers-supplier.jpg","width":776,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/www.jxscmachine.com\/new\/5-types-of-cone-crushers-comparison\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jxscmachine.com\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.jxscmachine.com\/new\/"},{"@type":"ListItem","position":3,"name":"5 Types of Cone Crushers Comparison"}]},{"@type":"WebSite","@id":"https:\/\/www.jxscmachine.com\/#website","url":"https:\/\/www.jxscmachine.com\/","name":"Machine JXSC","description":"Fabricant d&#039;\u00e9quipements de s\u00e9paration des min\u00e9raux depuis plus de 40 ans","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jxscmachine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.jxscmachine.com\/fr\/wp-json\/wp\/v2\/new\/8328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jxscmachine.com\/fr\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/www.jxscmachine.com\/fr\/wp-json\/wp\/v2\/types\/new"}],"author":[{"embeddable":true,"href":"https:\/\/www.jxscmachine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jxscmachine.com\/fr\/wp-json\/wp\/v2\/comments?post=8328"}],"version-history":[{"count":0,"href":"https:\/\/www.jxscmachine.com\/fr\/wp-json\/wp\/v2\/new\/8328\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jxscmachine.com\/fr\/wp-json\/wp\/v2\/media\/8350"}],"wp:attachment":[{"href":"https:\/\/www.jxscmachine.com\/fr\/wp-json\/wp\/v2\/media?parent=8328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jxscmachine.com\/fr\/wp-json\/wp\/v2\/categories?post=8328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jxscmachine.com\/fr\/wp-json\/wp\/v2\/tags?post=8328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}